{"id":8872,"date":"2017-06-06T06:38:07","date_gmt":"2017-06-06T06:38:07","guid":{"rendered":"https:\/\/isilos.ru\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php"},"modified":"2017-06-06T06:38:07","modified_gmt":"2017-06-06T06:38:07","slug":"%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81","status":"publish","type":"page","link":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php","title":{"rendered":"\u062a\u0635\u0645\u064a\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0645\u0632\u064a\u062c \u0627\u0644\u062c\u0627\u0641"},"content":{"rendered":"<p>\u062a\u0645 \u0625\u0646\u0634\u0627\u0621 \u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u0639\u0645\u0644\u0627\u0626\u0646\u0627 \u0648\u0647\u064a \u062a\u0639\u0645\u0644 \u0628\u0643\u0627\u0645\u0644 \u0637\u0627\u0642\u062a\u0647\u0627. \u0648\u0627\u0644\u063a\u0631\u0636 \u0645\u0646 \u0646\u0634\u0631 \u0647\u0630\u0647 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0647\u0648 \u0627\u0644\u062a\u0648\u0635\u064a\u0629 \u0628\u0646\u0627 \u0643\u0634\u0631\u0643\u0629 \u0645\u0635\u0646\u0639\u0629 \u0643\u0627\u0645\u0644\u0629 \u0644\u0644\u0645\u0635\u0627\u0646\u0639 \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0641\u062a\u062d \u0628\u0627\u0628 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0647\u0646\u062f\u0633\u064a\u0646 \u0648\u0627\u0644\u0645\u0637\u0648\u0631\u064a\u0646 \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062a\u0642\u062f\u0645 \u0628\u0634\u0643\u0644 \u0623\u0633\u0631\u0639 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u062c\u0627\u0644. <\/p>\n<p><a href=\"https:\/\/isilos.ru\/sss_plant.php\">\u0627\u0639\u0631\u0636 \u0648\u0635\u0641\u0627\u064b \u0643\u0627\u0645\u0644\u0627\u064b \u0644\u0645\u0635\u0627\u0646\u0639 CCC \u0627\u0644\u0646\u0645\u0648\u0630\u062c\u064a\u0629<\/a> &#8211; \u0643\u064a\u0641 \u064a\u062a\u0645 \u0625\u0639\u062f\u0627\u062f\u0647\u0627\u060c \u0648\u0645\u0627 \u0627\u0644\u0630\u064a \u062a\u062a\u0636\u0645\u0646\u0647\u060c \u0648\u0627\u0644\u0623\u0633\u0639\u0627\u0631\u060c \u0648\u0645\u0627 \u0625\u0644\u0649 \u0630\u0644\u0643.<\/p>\n<p>\u0641\u064a \u0627\u0644\u0641\u064a\u062f\u064a\u0648\u060c \u064a\u0634\u0631\u062d \u0643\u0628\u064a\u0631 \u0645\u0647\u0646\u062f\u0633\u064a \u0627\u0644\u0645\u0635\u0646\u0639 \u0628\u0627\u0644\u062a\u0641\u0635\u064a\u0644 \u0645\u0627 \u0647\u064a \u0627\u0644\u0645\u0635\u0627\u0646\u0639 \u0627\u0644\u062a\u064a \u062a\u0623\u062a\u064a \u0641\u064a \u0623\u064a \u062a\u062e\u0637\u064a\u0637\u0627\u062a\u060c \u0648\u0645\u0627 \u0647\u064a \u0627\u0644\u062a\u062c\u0645\u064a\u0639\u0627\u062a \u0627\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u0629 \u0641\u064a\u0647\u0627\u060c \u0648\u0623\u0643\u062b\u0631 \u0645\u0646 \u0630\u0644\u0643.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/8DLWbHBJYMI\" width=\"560\" height=\"314\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>\u0645\u0635\u0646\u0639 \u0644\u0643\u0631\u063a\u0627\u0646<\/h2>\n<div class=\"rl-gallery-container rl-loading\" id=\"rl-gallery-container-1\" data-gallery_id=\"4321\"> <div class=\"rl-gallery rl-basicgrid-gallery \" id=\"rl-gallery-1\" data-gallery_no=\"1\"> <div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/1-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/1-1-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/10-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/10-1-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/11-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/11-1-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/12-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/12-1-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/13.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/13-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/14.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/14-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/15.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/15-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/16.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/16-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/17.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/17-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/18.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/18-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/19.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/19-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/2-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/2-1-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/20.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/20-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/21.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/21-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/22.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/22-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/23.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/23-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/24.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/24-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/25.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/25-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/26.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/26-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/27.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/27-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/3-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/3-1-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/30.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/30-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/31.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/31-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/32.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/32-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/33.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/33-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/34.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/34-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/35.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/35-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/36.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/36-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/37.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/37-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/38.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/38-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/39.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/39-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/4-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/4-1-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/40.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/40-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/41.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/41-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/42.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/42-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/43.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/43-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/44.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/44-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/45.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/45-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/46.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/46-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/47.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/47-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/48.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/48-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/49.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/49-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/5-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/5-1-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/50.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/50-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/51.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/51-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/52.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/52-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/53.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/53-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/54.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/54-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/55.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/55-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/56.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/56-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/57.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/57-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/58.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/58-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/59.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/59-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/6-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/6-1-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/60.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/60-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/61.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/61-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/62.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/62-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/63.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/63-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/64.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/64-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/65.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/65-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/67.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/67-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/66.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/66-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/68.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/68-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/69.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/69-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/7-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/7-1-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/70.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/70-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/71.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/71-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/72.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/72-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/73.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/73-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/74.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/74-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/75.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/75-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/76.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/76-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/77.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/77-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/78.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/78-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/80.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/80-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/8-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/8-1-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/81.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/81-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/82.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/82-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/83.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/83-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/84.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/84-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/85.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/85-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/86.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/86-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/87.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/87-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/88.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/88-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/9-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0x\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/9-1-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" \/><\/a><\/div> <\/div> <\/div>\n<h2>\u0645\u0635\u0646\u0639 \u0644\u0623\u0648\u0631\u0627\u0644\u0633\u0643 (\u0643\u0627\u0632\u0627\u062e\u0633\u062a\u0627\u0646)\u060c \u062a\u062e\u0637\u064a\u0637 \u0623\u0641\u0642\u064a<\/h2>\n<div class=\"rl-gallery-container rl-loading\" id=\"rl-gallery-container-2\" data-gallery_id=\"4233\"> <div class=\"rl-gallery rl-basicgrid-gallery \" id=\"rl-gallery-2\" data-gallery_no=\"2\"> <div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0y\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/1-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/10.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0y\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/10-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/11.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0y\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/11-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/12.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0y\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/12-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/2.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0y\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/2-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/3.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0y\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/3-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/4.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0y\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/4-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/5.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0y\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/5-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/6.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0y\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/6-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/7.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0y\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/7-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/8.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0y\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/8-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/9.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0y\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2023\/03\/9-300x232.jpg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div> <\/div> <\/div>\n<h2>\u0645\u0635\u0646\u0639 \u0646\u064a\u062c\u0646\u064a \u062a\u0627\u062c\u064a\u0644\u060c \u0628\u062a\u0645\u0648\u064a\u0644 \u0645\u0646 \u0634\u0631\u0643\u0629 \u0633\u064a\u0645\u0646\u0632 \u0644\u0644\u062a\u0645\u0648\u064a\u0644<\/h2>\n<div class=\"rl-gallery-container rl-loading\" id=\"rl-gallery-container-3\" data-gallery_id=\"4215\"> <div class=\"rl-gallery rl-basicgrid-gallery \" id=\"rl-gallery-3\" data-gallery_no=\"3\"> <div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.34.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.34-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\u0447\u0435\u0440\u0442\u0435\u0436 \u0437\u0430\u0432\u043e\u0434\u0430 \u0441\u0443\u0445\u0438\u0445 \u0441\u043c\u0435\u0441\u0435\u0439\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.42.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.42-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.46.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.46-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.47.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.47-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.49.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.49-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.51.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.51-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.53.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.53-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.54.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.54-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\u0437\u0430\u0432\u043e\u0434 \u0441\u0443\u0445\u0438\u0445 \u0441\u0442\u0440\u043e\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0445 \u0441\u043c\u0435\u0441\u0435\u0439 3\u0434 \u043c\u043e\u0434\u0435\u043b\u044c\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.56.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.56-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.59.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.34.59-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.02.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.02-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.04.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.04-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.07.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.07-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.09.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.09-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.10.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.10-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.22.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.22-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.26.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.26-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.28.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.28-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.30.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.30-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.32.jpeg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS0z\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2021\/12\/photo_2021-12-05-11.35.32-300x232.jpeg\" width=\"300\" height=\"232\" alt=\"\" \/><\/a><\/div> <\/div> <\/div>\n<h2>\u0645\u0635\u0646\u0639 \u0627\u0644\u062e\u0644\u0637 \u0627\u0644\u062c\u0627\u0641 \u0644\u0623\u0628\u0627\u0643\u0627\u0646\u060c \u0627\u0644\u062a\u062e\u0637\u064a\u0637 \u0627\u0644\u0623\u0641\u0642\u064a<\/h2>\n<p>\u0627\u0644\u0633\u0639\u0629 25 \u0637\u0646\u064b\u0627 \u0641\u064a \u0627\u0644\u0633\u0627\u0639\u0629\u060c \u0627\u0644\u0645\u0635\u0646\u0639 \u0623\u0648\u062a\u0648\u0645\u0627\u062a\u064a\u0643\u064a \u0628\u0627\u0644\u0643\u0627\u0645\u0644\u060c \u062c\u0631\u0639\u0627\u062a \u0627\u0644\u0645\u0648\u0627\u062f \u0627\u0644\u0645\u0636\u0627\u0641\u0629 \u0623\u0648\u062a\u0648\u0645\u0627\u062a\u064a\u0643\u064a\u0629. \u0627\u0644\u0645\u0635\u0646\u0639 \u0645\u0632\u0648\u062f \u0628\u0623\u0633\u0637\u0648\u0627\u0646\u0629 \u062a\u062c\u0641\u064a\u0641 \u0627\u0644\u0631\u0645\u0627\u0644. <\/p>\n<div class=\"rl-gallery-container rl-loading\" id=\"rl-gallery-container-4\" data-gallery_id=\"4217\"> <div class=\"rl-gallery rl-basicgrid-gallery \" id=\"rl-gallery-4\" data-gallery_no=\"4\"> <div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/\u043f\u0440\u043e\u0435\u043a\u0442-\u0437\u0430\u0432\u043e\u0434\u0430-3\u0434-\u043c\u043e\u0434\u0435\u043b\u044c.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS00\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/\u043f\u0440\u043e\u0435\u043a\u0442-\u0437\u0430\u0432\u043e\u0434\u0430-3\u0434-\u043c\u043e\u0434\u0435\u043b\u044c-300x190.jpg\" width=\"300\" height=\"190\" alt=\"\u043f\u0440\u043e\u0435\u043a\u0442 \u0437\u0430\u0432\u043e\u0434\u0430 \u0441\u0443\u0445\u0438\u0445 \u0441\u043c\u0435\u0441\u0435\u0439 \u043c\u043e\u0434\u0435\u043b\u044c\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/4.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS00\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/4-300x177.jpg\" width=\"300\" height=\"177\" alt=\"\u043c\u043e\u0434\u0435\u043b\u044c \u0437\u0430\u0432\u043e\u0434\u0430 \u0441\u0443\u0445\u0438\u0445 \u0441\u043c\u0435\u0441\u0435\u0439\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/3.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS00\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/3-300x177.jpg\" width=\"300\" height=\"177\" alt=\"\u043c\u043e\u0434\u0435\u043b\u044c \u0437\u0430\u0432\u043e\u0434\u0430 \u0441\u0443\u0445\u0438\u0445 \u0441\u043c\u0435\u0441\u0435\u0439\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/2.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS00\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/2-300x177.jpg\" width=\"300\" height=\"177\" alt=\"\u043c\u043e\u0434\u0435\u043b\u044c \u0437\u0430\u0432\u043e\u0434\u0430 \u0441\u0443\u0445\u0438\u0445 \u0441\u043c\u0435\u0441\u0435\u0439\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS00\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/1-300x177.jpg\" width=\"300\" height=\"177\" alt=\"\u043c\u043e\u0434\u0435\u043b\u044c \u0437\u0430\u0432\u043e\u0434\u0430 \u0441\u0443\u0445\u0438\u0445 \u0441\u043c\u0435\u0441\u0435\u0439\" \/><\/a><\/div> <\/div> <\/div>\n<h2>\u0645\u0635\u0646\u0639 \u0627\u0644\u062e\u0644\u0637 \u0627\u0644\u062c\u0627\u0641 \u0644\u0625\u064a\u0643\u0627\u062a\u0631\u064a\u0646\u0628\u0631\u063a\u060c \u062a\u062e\u0637\u064a\u0637 \u0631\u0623\u0633\u064a<\/h2>\n<p>\u0627\u0644\u0633\u0639\u0629 20 \u0637\u0646\u0627\u064b \u0641\u064a \u0627\u0644\u0633\u0627\u0639\u0629\u060c \u0623\u0648\u062a\u0648\u0645\u0627\u062a\u064a\u0643\u064a \u0628\u0627\u0644\u0643\u0627\u0645\u0644\u060c \u0627\u0644\u062c\u0631\u0639\u0627\u062a \u0627\u0644\u0645\u0636\u0627\u0641\u0629 \u0623\u0648\u062a\u0648\u0645\u0627\u062a\u064a\u0643\u064a\u0629. \u0645\u0635\u0646\u0639 \u0645\u0632\u0648\u062f \u0628\u0623\u0633\u0637\u0648\u0627\u0646\u0629 \u062a\u062c\u0641\u064a\u0641 \u0627\u0644\u0631\u0645\u0627\u0644. <\/p>\n<div class=\"rl-gallery-container rl-loading\" id=\"rl-gallery-container-5\" data-gallery_id=\"4219\"> <div class=\"rl-gallery rl-basicgrid-gallery \" id=\"rl-gallery-5\" data-gallery_no=\"5\"> <div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/5.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS01\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/5-300x159.jpg\" width=\"300\" height=\"159\" alt=\"\u043b\u0438\u043d\u0438\u044f \u0441\u0443\u0445\u0438\u0445 \u0441\u0442\u0440\u043e\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0445 \u0441\u043c\u0435\u0441\u0435\u0439\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/4-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS01\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/4-1-300x159.jpg\" width=\"300\" height=\"159\" alt=\"\u043b\u0438\u043d\u0438\u044f \u0441\u0443\u0445\u0438\u0445 \u0441\u0442\u0440\u043e\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0445 \u0441\u043c\u0435\u0441\u0435\u0439\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/3-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS01\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/3-1-300x159.jpg\" width=\"300\" height=\"159\" alt=\"\u043b\u0438\u043d\u0438\u044f \u0441\u0443\u0445\u0438\u0445 \u0441\u0442\u0440\u043e\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0445 \u0441\u043c\u0435\u0441\u0435\u0439\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/2-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS01\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/2-1-300x159.jpg\" width=\"300\" height=\"159\" alt=\"\u043b\u0438\u043d\u0438\u044f \u0441\u0443\u0445\u0438\u0445 \u0441\u0442\u0440\u043e\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0445 \u0441\u043c\u0435\u0441\u0435\u0439\" \/><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/1-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-bGlnaHRib3gtZ2FsbGVyeS01\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/1-1-300x159.jpg\" width=\"300\" height=\"159\" alt=\"\u043b\u0438\u043d\u0438\u044f \u0441\u0443\u0445\u0438\u0445 \u0441\u0442\u0440\u043e\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0445 \u0441\u043c\u0435\u0441\u0435\u0439\" \/><\/a><\/div> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u062a\u0645 \u0625\u0646\u0634\u0627\u0621 \u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u0639\u0645\u0644\u0627\u0626\u0646\u0627 \u0648\u0647\u064a \u062a\u0639\u0645\u0644 \u0628\u0643\u0627\u0645\u0644 \u0637\u0627\u0642\u062a\u0647\u0627. \u0648\u0627\u0644\u063a\u0631\u0636 \u0645\u0646 \u0646\u0634\u0631 \u0647\u0630\u0647 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0647\u0648 \u0627\u0644\u062a\u0648\u0635\u064a\u0629 \u0628\u0646\u0627 \u0643\u0634\u0631\u0643\u0629 \u0645\u0635\u0646\u0639\u0629 \u0643\u0627\u0645\u0644\u0629 \u0644\u0644\u0645\u0635\u0627\u0646\u0639 \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0641\u062a\u062d \u0628\u0627\u0628 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0647\u0646\u062f\u0633\u064a\u0646 \u0648\u0627\u0644\u0645\u0637\u0648\u0631\u064a\u0646 \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062a\u0642\u062f\u0645 \u0628\u0634\u0643\u0644 \u0623\u0633\u0631\u0639 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u062c\u0627\u0644. \u0627\u0639\u0631\u0636 \u0648\u0635\u0641\u0627\u064b \u0643\u0627\u0645\u0644\u0627\u064b \u0644\u0645\u0635\u0627\u0646\u0639 CCC \u0627\u0644\u0646\u0645\u0648\u0630\u062c\u064a\u0629 &#8211; \u0643\u064a\u0641 \u064a\u062a\u0645 \u0625\u0639\u062f\u0627\u062f\u0647\u0627\u060c \u0648\u0645\u0627 \u0627\u0644\u0630\u064a \u062a\u062a\u0636\u0645\u0646\u0647\u060c \u0648\u0627\u0644\u0623\u0633\u0639\u0627\u0631\u060c \u0648\u0645\u0627 \u0625\u0644\u0649 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6779,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8872","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u062a\u0645 \u0625\u0646\u0634\u0627\u0621 \u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u0639\u0645\u0644\u0627\u0626\u0646\u0627 \u0648\u0647\u064a \u062a\u0639\u0645\u0644 \u0628\u0643\u0627\u0645\u0644 \u0637\u0627\u0642\u062a\u0647\u0627. \u0648\u0627\u0644\u063a\u0631\u0636 \u0645\u0646 \u0646\u0634\u0631 \u0647\u0630\u0647 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0647\u0648 \u0627\u0644\u062a\u0648\u0635\u064a\u0629 \u0628\u0646\u0627 \u0643\u0634\u0631\u0643\u0629 \u0645\u0635\u0646\u0639\u0629 \u0643\u0627\u0645\u0644\u0629 \u0644\u0644\u0645\u0635\u0627\u0646\u0639 \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0641\u062a\u062d \u0628\u0627\u0628 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0647\u0646\u062f\u0633\u064a\u0646 \u0648\u0627\u0644\u0645\u0637\u0648\u0631\u064a\u0646 \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062a\u0642\u062f\u0645 \u0628\u0634\u0643\u0644 \u0623\u0633\u0631\u0639 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u062c\u0627\u0644. \u0627\u0639\u0631\u0636 \u0648\u0635\u0641\u0627\u064b \u0643\u0627\u0645\u0644\u0627\u064b \u0644\u0645\u0635\u0627\u0646\u0639 CCC \u0627\u0644\u0646\u0645\u0648\u0630\u062c\u064a\u0629 - \u0643\u064a\u0641 \u064a\u062a\u0645 \u0625\u0639\u062f\u0627\u062f\u0647\u0627\u060c \u0648\u0645\u0627 \u0627\u0644\u0630\u064a \u062a\u062a\u0636\u0645\u0646\u0647\u060c \u0648\u0627\u0644\u0623\u0633\u0639\u0627\u0631\u060c \u0648\u0645\u0627 \u0625\u0644\u0649\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"ar_AR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\u0417\u0430\u0432\u043e\u0434 \u0410\u0410\u041c\u0438\u043a\u0441\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u062a\u0635\u0645\u064a\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0645\u0632\u064a\u062c \u0627\u0644\u062c\u0627\u0641\" \/>\n\t\t<meta property=\"og:description\" content=\"\u062a\u0645 \u0625\u0646\u0634\u0627\u0621 \u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u0639\u0645\u0644\u0627\u0626\u0646\u0627 \u0648\u0647\u064a \u062a\u0639\u0645\u0644 \u0628\u0643\u0627\u0645\u0644 \u0637\u0627\u0642\u062a\u0647\u0627. \u0648\u0627\u0644\u063a\u0631\u0636 \u0645\u0646 \u0646\u0634\u0631 \u0647\u0630\u0647 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0647\u0648 \u0627\u0644\u062a\u0648\u0635\u064a\u0629 \u0628\u0646\u0627 \u0643\u0634\u0631\u0643\u0629 \u0645\u0635\u0646\u0639\u0629 \u0643\u0627\u0645\u0644\u0629 \u0644\u0644\u0645\u0635\u0627\u0646\u0639 \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0641\u062a\u062d \u0628\u0627\u0628 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0647\u0646\u062f\u0633\u064a\u0646 \u0648\u0627\u0644\u0645\u0637\u0648\u0631\u064a\u0646 \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062a\u0642\u062f\u0645 \u0628\u0634\u0643\u0644 \u0623\u0633\u0631\u0639 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u062c\u0627\u0644. \u0627\u0639\u0631\u0636 \u0648\u0635\u0641\u0627\u064b \u0643\u0627\u0645\u0644\u0627\u064b \u0644\u0645\u0635\u0627\u0646\u0639 CCC \u0627\u0644\u0646\u0645\u0648\u0630\u062c\u064a\u0629 - \u0643\u064a\u0641 \u064a\u062a\u0645 \u0625\u0639\u062f\u0627\u062f\u0647\u0627\u060c \u0648\u0645\u0627 \u0627\u0644\u0630\u064a \u062a\u062a\u0636\u0645\u0646\u0647\u060c \u0648\u0627\u0644\u0623\u0633\u0639\u0627\u0631\u060c \u0648\u0645\u0627 \u0625\u0644\u0649\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"364\" \/>\n\t\t<meta property=\"og:image:height\" content=\"94\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-06-06T06:38:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-06-06T06:38:07+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u062a\u0635\u0645\u064a\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0645\u0632\u064a\u062c \u0627\u0644\u062c\u0627\u0641\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u062a\u0645 \u0625\u0646\u0634\u0627\u0621 \u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u0639\u0645\u0644\u0627\u0626\u0646\u0627 \u0648\u0647\u064a \u062a\u0639\u0645\u0644 \u0628\u0643\u0627\u0645\u0644 \u0637\u0627\u0642\u062a\u0647\u0627. \u0648\u0627\u0644\u063a\u0631\u0636 \u0645\u0646 \u0646\u0634\u0631 \u0647\u0630\u0647 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0647\u0648 \u0627\u0644\u062a\u0648\u0635\u064a\u0629 \u0628\u0646\u0627 \u0643\u0634\u0631\u0643\u0629 \u0645\u0635\u0646\u0639\u0629 \u0643\u0627\u0645\u0644\u0629 \u0644\u0644\u0645\u0635\u0627\u0646\u0639 \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0641\u062a\u062d \u0628\u0627\u0628 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0647\u0646\u062f\u0633\u064a\u0646 \u0648\u0627\u0644\u0645\u0637\u0648\u0631\u064a\u0646 \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062a\u0642\u062f\u0645 \u0628\u0634\u0643\u0644 \u0623\u0633\u0631\u0639 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u062c\u0627\u0644. \u0627\u0639\u0631\u0636 \u0648\u0635\u0641\u0627\u064b \u0643\u0627\u0645\u0644\u0627\u064b \u0644\u0645\u0635\u0627\u0646\u0639 CCC \u0627\u0644\u0646\u0645\u0648\u0630\u062c\u064a\u0629 - \u0643\u064a\u0641 \u064a\u062a\u0645 \u0625\u0639\u062f\u0627\u062f\u0647\u0627\u060c \u0648\u0645\u0627 \u0627\u0644\u0630\u064a \u062a\u062a\u0636\u0645\u0646\u0647\u060c \u0648\u0627\u0644\u0623\u0633\u0639\u0627\u0631\u060c \u0648\u0645\u0627 \u0625\u0644\u0649\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar#listItem\",\"position\":1,\"name\":\"\\u0413\\u043b\\u0430\\u0432\\u043d\\u0430\\u044f\",\"item\":\"https:\\\/\\\/isilos.ru\\\/ar\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php#listItem\",\"name\":\"\\u062a\\u0635\\u0645\\u064a\\u0645\\u0627\\u062a \\u062e\\u0637\\u0648\\u0637 \\u0625\\u0646\\u062a\\u0627\\u062c \\u0627\\u0644\\u0645\\u0632\\u064a\\u062c \\u0627\\u0644\\u062c\\u0627\\u0641\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php#listItem\",\"position\":2,\"name\":\"\\u062a\\u0635\\u0645\\u064a\\u0645\\u0627\\u062a \\u062e\\u0637\\u0648\\u0637 \\u0625\\u0646\\u062a\\u0627\\u062c \\u0627\\u0644\\u0645\\u0632\\u064a\\u062c \\u0627\\u0644\\u062c\\u0627\\u0641\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar#listItem\",\"name\":\"\\u0413\\u043b\\u0430\\u0432\\u043d\\u0430\\u044f\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/#organization\",\"name\":\"\\u041d\\u041f\\u041e \\u0417\\u0430\\u0432\\u043e\\u0434 \\u0410\\u0410\\u041c\\u0438\\u043a\\u0441\",\"description\":\"\\u041f\\u0440\\u043e\\u0438\\u0437\\u0432\\u043e\\u0434\\u0438\\u0442\\u0435\\u043b\\u044c \\u043f\\u0440\\u043e\\u043c\\u044b\\u0448\\u043b\\u0435\\u043d\\u043d\\u043e\\u0433\\u043e \\u043e\\u0431\\u043e\\u0440\\u0443\\u0434\\u043e\\u0432\\u0430\\u043d\\u0438\\u044f, \\u043a\\u043e\\u043c\\u043f\\u043b\\u0435\\u043a\\u0442\\u043d\\u044b\\u0445 \\u0437\\u0430\\u0432\\u043e\\u0434\\u043e\\u0432 \\u0441\\u0443\\u0445\\u0438\\u0445 \\u0441\\u043c\\u0435\\u0441\\u0435\\u0439, \\u0441\\u043c\\u0435\\u0441\\u0438\\u0442\\u0435\\u043b\\u0435\\u0439, \\u0434\\u043e\\u0437\\u0430\\u0442\\u043e\\u0440\\u043e\\u0432, \\u0441\\u0438\\u043b\\u043e\\u0441\\u043e\\u0432, \\u0444\\u0430\\u0441\\u043e\\u0432\\u043e\\u0447\\u043d\\u044b\\u0445 \\u043b\\u0438\\u043d\\u0438\\u0439 \\u0438 \\u0441\\u0438\\u0441\\u0442\\u0435\\u043c \\u0430\\u0432\\u0442\\u043e\\u043c\\u0430\\u0442\\u0438\\u0437\\u0430\\u0446\\u0438\\u0438.\",\"url\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/\",\"email\":\"info@isilos.ru\",\"telephone\":\"+7 (812) 408-41-82\",\"foundingDate\":\"1999\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/isilos.ru\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-logo.png\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php\\\/#organizationLogo\",\"width\":364,\"height\":94},\"image\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/@aamixplant\",\"https:\\\/\\\/t.me\\\/aamixplant\",\"https:\\\/\\\/isilos.ru\\\/contact.php\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php#webpage\",\"url\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php\",\"name\":\"\\u062a\\u0635\\u0645\\u064a\\u0645\\u0627\\u062a \\u062e\\u0637\\u0648\\u0637 \\u0625\\u0646\\u062a\\u0627\\u062c \\u0627\\u0644\\u0645\\u0632\\u064a\\u062c \\u0627\\u0644\\u062c\\u0627\\u0641\",\"description\":\"\\u062a\\u0645 \\u0625\\u0646\\u0634\\u0627\\u0621 \\u062c\\u0645\\u064a\\u0639 \\u0627\\u0644\\u0645\\u0634\\u0627\\u0631\\u064a\\u0639 \\u0644\\u0639\\u0645\\u0644\\u0627\\u0626\\u0646\\u0627 \\u0648\\u0647\\u064a \\u062a\\u0639\\u0645\\u0644 \\u0628\\u0643\\u0627\\u0645\\u0644 \\u0637\\u0627\\u0642\\u062a\\u0647\\u0627. \\u0648\\u0627\\u0644\\u063a\\u0631\\u0636 \\u0645\\u0646 \\u0646\\u0634\\u0631 \\u0647\\u0630\\u0647 \\u0627\\u0644\\u0645\\u0634\\u0627\\u0631\\u064a\\u0639 \\u0647\\u0648 \\u0627\\u0644\\u062a\\u0648\\u0635\\u064a\\u0629 \\u0628\\u0646\\u0627 \\u0643\\u0634\\u0631\\u0643\\u0629 \\u0645\\u0635\\u0646\\u0639\\u0629 \\u0643\\u0627\\u0645\\u0644\\u0629 \\u0644\\u0644\\u0645\\u0635\\u0627\\u0646\\u0639 \\u0628\\u0627\\u0644\\u0625\\u0636\\u0627\\u0641\\u0629 \\u0625\\u0644\\u0649 \\u0641\\u062a\\u062d \\u0628\\u0627\\u0628 \\u0627\\u0644\\u0648\\u0635\\u0648\\u0644 \\u0625\\u0644\\u0649 \\u0627\\u0644\\u0645\\u0634\\u0627\\u0631\\u064a\\u0639 \\u0644\\u062c\\u0645\\u064a\\u0639 \\u0627\\u0644\\u0645\\u0647\\u0646\\u062f\\u0633\\u064a\\u0646 \\u0648\\u0627\\u0644\\u0645\\u0637\\u0648\\u0631\\u064a\\u0646 \\u0645\\u0646 \\u0623\\u062c\\u0644 \\u0627\\u0644\\u062a\\u0642\\u062f\\u0645 \\u0628\\u0634\\u0643\\u0644 \\u0623\\u0633\\u0631\\u0639 \\u0641\\u064a \\u0647\\u0630\\u0627 \\u0627\\u0644\\u0645\\u062c\\u0627\\u0644. \\u0627\\u0639\\u0631\\u0636 \\u0648\\u0635\\u0641\\u0627\\u064b \\u0643\\u0627\\u0645\\u0644\\u0627\\u064b \\u0644\\u0645\\u0635\\u0627\\u0646\\u0639 CCC \\u0627\\u0644\\u0646\\u0645\\u0648\\u0630\\u062c\\u064a\\u0629 - \\u0643\\u064a\\u0641 \\u064a\\u062a\\u0645 \\u0625\\u0639\\u062f\\u0627\\u062f\\u0647\\u0627\\u060c \\u0648\\u0645\\u0627 \\u0627\\u0644\\u0630\\u064a \\u062a\\u062a\\u0636\\u0645\\u0646\\u0647\\u060c \\u0648\\u0627\\u0644\\u0623\\u0633\\u0639\\u0627\\u0631\\u060c \\u0648\\u0645\\u0627 \\u0625\\u0644\\u0649\",\"inLanguage\":\"ar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/isilos.ru\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/3.jpg\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php\\\/#mainImage\",\"width\":1600,\"height\":943,\"caption\":\"\\u043c\\u043e\\u0434\\u0435\\u043b\\u044c \\u0437\\u0430\\u0432\\u043e\\u0434\\u0430 \\u0441\\u0443\\u0445\\u0438\\u0445 \\u0441\\u043c\\u0435\\u0441\\u0435\\u0439\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php#mainImage\"},\"datePublished\":\"2017-06-06T06:38:07+00:00\",\"dateModified\":\"2017-06-06T06:38:07+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/\",\"name\":\"\\u0417\\u0430\\u0432\\u043e\\u0434 \\u0410\\u0410\\u041c\\u0438\\u043a\\u0441\",\"alternateName\":\"AAMix, \\u0410\\u0410\\u041c\\u0438\\u043a\\u0441\",\"inLanguage\":\"ar\",\"publisher\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/ar\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u062a\u0635\u0645\u064a\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0645\u0632\u064a\u062c \u0627\u0644\u062c\u0627\u0641","description":"\u062a\u0645 \u0625\u0646\u0634\u0627\u0621 \u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u0639\u0645\u0644\u0627\u0626\u0646\u0627 \u0648\u0647\u064a \u062a\u0639\u0645\u0644 \u0628\u0643\u0627\u0645\u0644 \u0637\u0627\u0642\u062a\u0647\u0627. \u0648\u0627\u0644\u063a\u0631\u0636 \u0645\u0646 \u0646\u0634\u0631 \u0647\u0630\u0647 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0647\u0648 \u0627\u0644\u062a\u0648\u0635\u064a\u0629 \u0628\u0646\u0627 \u0643\u0634\u0631\u0643\u0629 \u0645\u0635\u0646\u0639\u0629 \u0643\u0627\u0645\u0644\u0629 \u0644\u0644\u0645\u0635\u0627\u0646\u0639 \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0641\u062a\u062d \u0628\u0627\u0628 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0647\u0646\u062f\u0633\u064a\u0646 \u0648\u0627\u0644\u0645\u0637\u0648\u0631\u064a\u0646 \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062a\u0642\u062f\u0645 \u0628\u0634\u0643\u0644 \u0623\u0633\u0631\u0639 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u062c\u0627\u0644. \u0627\u0639\u0631\u0636 \u0648\u0635\u0641\u0627\u064b \u0643\u0627\u0645\u0644\u0627\u064b \u0644\u0645\u0635\u0627\u0646\u0639 CCC \u0627\u0644\u0646\u0645\u0648\u0630\u062c\u064a\u0629 - \u0643\u064a\u0641 \u064a\u062a\u0645 \u0625\u0639\u062f\u0627\u062f\u0647\u0627\u060c \u0648\u0645\u0627 \u0627\u0644\u0630\u064a \u062a\u062a\u0636\u0645\u0646\u0647\u060c \u0648\u0627\u0644\u0623\u0633\u0639\u0627\u0631\u060c \u0648\u0645\u0627 \u0625\u0644\u0649","canonical_url":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/isilos.ru\/ar#listItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f","item":"https:\/\/isilos.ru\/ar","nextItem":{"@type":"ListItem","@id":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php#listItem","name":"\u062a\u0635\u0645\u064a\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0645\u0632\u064a\u062c \u0627\u0644\u062c\u0627\u0641"}},{"@type":"ListItem","@id":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php#listItem","position":2,"name":"\u062a\u0635\u0645\u064a\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0645\u0632\u064a\u062c \u0627\u0644\u062c\u0627\u0641","previousItem":{"@type":"ListItem","@id":"https:\/\/isilos.ru\/ar#listItem","name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f"}}]},{"@type":"Organization","@id":"https:\/\/isilos.ru\/ar\/#organization","name":"\u041d\u041f\u041e \u0417\u0430\u0432\u043e\u0434 \u0410\u0410\u041c\u0438\u043a\u0441","description":"\u041f\u0440\u043e\u0438\u0437\u0432\u043e\u0434\u0438\u0442\u0435\u043b\u044c \u043f\u0440\u043e\u043c\u044b\u0448\u043b\u0435\u043d\u043d\u043e\u0433\u043e \u043e\u0431\u043e\u0440\u0443\u0434\u043e\u0432\u0430\u043d\u0438\u044f, \u043a\u043e\u043c\u043f\u043b\u0435\u043a\u0442\u043d\u044b\u0445 \u0437\u0430\u0432\u043e\u0434\u043e\u0432 \u0441\u0443\u0445\u0438\u0445 \u0441\u043c\u0435\u0441\u0435\u0439, \u0441\u043c\u0435\u0441\u0438\u0442\u0435\u043b\u0435\u0439, \u0434\u043e\u0437\u0430\u0442\u043e\u0440\u043e\u0432, \u0441\u0438\u043b\u043e\u0441\u043e\u0432, \u0444\u0430\u0441\u043e\u0432\u043e\u0447\u043d\u044b\u0445 \u043b\u0438\u043d\u0438\u0439 \u0438 \u0441\u0438\u0441\u0442\u0435\u043c \u0430\u0432\u0442\u043e\u043c\u0430\u0442\u0438\u0437\u0430\u0446\u0438\u0438.","url":"https:\/\/isilos.ru\/ar\/","email":"info@isilos.ru","telephone":"+7 (812) 408-41-82","foundingDate":"1999","logo":{"@type":"ImageObject","url":"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png","@id":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php\/#organizationLogo","width":364,"height":94},"image":{"@id":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php\/#organizationLogo"},"sameAs":["https:\/\/www.youtube.com\/@aamixplant","https:\/\/t.me\/aamixplant","https:\/\/isilos.ru\/contact.php"]},{"@type":"WebPage","@id":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php#webpage","url":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php","name":"\u062a\u0635\u0645\u064a\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0645\u0632\u064a\u062c \u0627\u0644\u062c\u0627\u0641","description":"\u062a\u0645 \u0625\u0646\u0634\u0627\u0621 \u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u0639\u0645\u0644\u0627\u0626\u0646\u0627 \u0648\u0647\u064a \u062a\u0639\u0645\u0644 \u0628\u0643\u0627\u0645\u0644 \u0637\u0627\u0642\u062a\u0647\u0627. \u0648\u0627\u0644\u063a\u0631\u0636 \u0645\u0646 \u0646\u0634\u0631 \u0647\u0630\u0647 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0647\u0648 \u0627\u0644\u062a\u0648\u0635\u064a\u0629 \u0628\u0646\u0627 \u0643\u0634\u0631\u0643\u0629 \u0645\u0635\u0646\u0639\u0629 \u0643\u0627\u0645\u0644\u0629 \u0644\u0644\u0645\u0635\u0627\u0646\u0639 \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0641\u062a\u062d \u0628\u0627\u0628 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0647\u0646\u062f\u0633\u064a\u0646 \u0648\u0627\u0644\u0645\u0637\u0648\u0631\u064a\u0646 \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062a\u0642\u062f\u0645 \u0628\u0634\u0643\u0644 \u0623\u0633\u0631\u0639 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u062c\u0627\u0644. \u0627\u0639\u0631\u0636 \u0648\u0635\u0641\u0627\u064b \u0643\u0627\u0645\u0644\u0627\u064b \u0644\u0645\u0635\u0627\u0646\u0639 CCC \u0627\u0644\u0646\u0645\u0648\u0630\u062c\u064a\u0629 - \u0643\u064a\u0641 \u064a\u062a\u0645 \u0625\u0639\u062f\u0627\u062f\u0647\u0627\u060c \u0648\u0645\u0627 \u0627\u0644\u0630\u064a \u062a\u062a\u0636\u0645\u0646\u0647\u060c \u0648\u0627\u0644\u0623\u0633\u0639\u0627\u0631\u060c \u0648\u0645\u0627 \u0625\u0644\u0649","inLanguage":"ar","isPartOf":{"@id":"https:\/\/isilos.ru\/ar\/#website"},"breadcrumb":{"@id":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/isilos.ru\/wp-content\/uploads\/2017\/06\/3.jpg","@id":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php\/#mainImage","width":1600,"height":943,"caption":"\u043c\u043e\u0434\u0435\u043b\u044c \u0437\u0430\u0432\u043e\u0434\u0430 \u0441\u0443\u0445\u0438\u0445 \u0441\u043c\u0435\u0441\u0435\u0439"},"primaryImageOfPage":{"@id":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php#mainImage"},"datePublished":"2017-06-06T06:38:07+00:00","dateModified":"2017-06-06T06:38:07+00:00"},{"@type":"WebSite","@id":"https:\/\/isilos.ru\/ar\/#website","url":"https:\/\/isilos.ru\/ar\/","name":"\u0417\u0430\u0432\u043e\u0434 \u0410\u0410\u041c\u0438\u043a\u0441","alternateName":"AAMix, \u0410\u0410\u041c\u0438\u043a\u0441","inLanguage":"ar","publisher":{"@id":"https:\/\/isilos.ru\/ar\/#organization"}}]},"og:locale":"ar_AR","og:site_name":"\u0417\u0430\u0432\u043e\u0434 \u0410\u0410\u041c\u0438\u043a\u0441","og:type":"article","og:title":"\u062a\u0635\u0645\u064a\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0645\u0632\u064a\u062c \u0627\u0644\u062c\u0627\u0641","og:description":"\u062a\u0645 \u0625\u0646\u0634\u0627\u0621 \u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u0639\u0645\u0644\u0627\u0626\u0646\u0627 \u0648\u0647\u064a \u062a\u0639\u0645\u0644 \u0628\u0643\u0627\u0645\u0644 \u0637\u0627\u0642\u062a\u0647\u0627. \u0648\u0627\u0644\u063a\u0631\u0636 \u0645\u0646 \u0646\u0634\u0631 \u0647\u0630\u0647 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0647\u0648 \u0627\u0644\u062a\u0648\u0635\u064a\u0629 \u0628\u0646\u0627 \u0643\u0634\u0631\u0643\u0629 \u0645\u0635\u0646\u0639\u0629 \u0643\u0627\u0645\u0644\u0629 \u0644\u0644\u0645\u0635\u0627\u0646\u0639 \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0641\u062a\u062d \u0628\u0627\u0628 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0647\u0646\u062f\u0633\u064a\u0646 \u0648\u0627\u0644\u0645\u0637\u0648\u0631\u064a\u0646 \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062a\u0642\u062f\u0645 \u0628\u0634\u0643\u0644 \u0623\u0633\u0631\u0639 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u062c\u0627\u0644. \u0627\u0639\u0631\u0636 \u0648\u0635\u0641\u0627\u064b \u0643\u0627\u0645\u0644\u0627\u064b \u0644\u0645\u0635\u0627\u0646\u0639 CCC \u0627\u0644\u0646\u0645\u0648\u0630\u062c\u064a\u0629 - \u0643\u064a\u0641 \u064a\u062a\u0645 \u0625\u0639\u062f\u0627\u062f\u0647\u0627\u060c \u0648\u0645\u0627 \u0627\u0644\u0630\u064a \u062a\u062a\u0636\u0645\u0646\u0647\u060c \u0648\u0627\u0644\u0623\u0633\u0639\u0627\u0631\u060c \u0648\u0645\u0627 \u0625\u0644\u0649","og:url":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php","og:image":"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png","og:image:secure_url":"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png","og:image:width":364,"og:image:height":94,"article:published_time":"2017-06-06T06:38:07+00:00","article:modified_time":"2017-06-06T06:38:07+00:00","twitter:card":"summary","twitter:title":"\u062a\u0635\u0645\u064a\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0645\u0632\u064a\u062c \u0627\u0644\u062c\u0627\u0641","twitter:description":"\u062a\u0645 \u0625\u0646\u0634\u0627\u0621 \u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u0639\u0645\u0644\u0627\u0626\u0646\u0627 \u0648\u0647\u064a \u062a\u0639\u0645\u0644 \u0628\u0643\u0627\u0645\u0644 \u0637\u0627\u0642\u062a\u0647\u0627. \u0648\u0627\u0644\u063a\u0631\u0636 \u0645\u0646 \u0646\u0634\u0631 \u0647\u0630\u0647 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0647\u0648 \u0627\u0644\u062a\u0648\u0635\u064a\u0629 \u0628\u0646\u0627 \u0643\u0634\u0631\u0643\u0629 \u0645\u0635\u0646\u0639\u0629 \u0643\u0627\u0645\u0644\u0629 \u0644\u0644\u0645\u0635\u0627\u0646\u0639 \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0641\u062a\u062d \u0628\u0627\u0628 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0644\u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0647\u0646\u062f\u0633\u064a\u0646 \u0648\u0627\u0644\u0645\u0637\u0648\u0631\u064a\u0646 \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062a\u0642\u062f\u0645 \u0628\u0634\u0643\u0644 \u0623\u0633\u0631\u0639 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u062c\u0627\u0644. \u0627\u0639\u0631\u0636 \u0648\u0635\u0641\u0627\u064b \u0643\u0627\u0645\u0644\u0627\u064b \u0644\u0645\u0635\u0627\u0646\u0639 CCC \u0627\u0644\u0646\u0645\u0648\u0630\u062c\u064a\u0629 - \u0643\u064a\u0641 \u064a\u062a\u0645 \u0625\u0639\u062f\u0627\u062f\u0647\u0627\u060c \u0648\u0645\u0627 \u0627\u0644\u0630\u064a \u062a\u062a\u0636\u0645\u0646\u0647\u060c \u0648\u0627\u0644\u0623\u0633\u0639\u0627\u0631\u060c \u0648\u0645\u0627 \u0625\u0644\u0649","twitter:image":"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png"},"aioseo_meta_data":{"post_id":"8872","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"aioseo-web-page-634c592e95cf0","slug":"web-page","graphName":"WebPage","label":"\u0412\u0435\u0431-\u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-07-11 15:51:52","updated":"2025-07-11 15:51:52","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/isilos.ru\/ar\" title=\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f\">\u0413\u043b\u0430\u0432\u043d\u0430\u044f<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u062a\u0635\u0645\u064a\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0645\u0632\u064a\u062c \u0627\u0644\u062c\u0627\u0641\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f","link":"https:\/\/isilos.ru\/ar"},{"label":"\u062a\u0635\u0645\u064a\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0645\u0632\u064a\u062c \u0627\u0644\u062c\u0627\u0641","link":"https:\/\/isilos.ru\/ar\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85%d8%a7%d8%aa-%d8%ae%d8%b7%d9%88%d8%b7-%d8%a5%d9%86%d8%aa%d8%a7%d8%ac-%d8%a7%d9%84%d9%85%d8%b2%d9%8a%d8%ac-%d8%a7%d9%84%d8%ac%d8%a7%d9%81.php"}],"_links":{"self":[{"href":"https:\/\/isilos.ru\/ar\/wp-json\/wp\/v2\/pages\/8872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isilos.ru\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/isilos.ru\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/isilos.ru\/ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/isilos.ru\/ar\/wp-json\/wp\/v2\/comments?post=8872"}],"version-history":[{"count":0,"href":"https:\/\/isilos.ru\/ar\/wp-json\/wp\/v2\/pages\/8872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isilos.ru\/ar\/wp-json\/wp\/v2\/media\/6779"}],"wp:attachment":[{"href":"https:\/\/isilos.ru\/ar\/wp-json\/wp\/v2\/media?parent=8872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}