{"id":9758,"date":"2018-10-29T15:07:04","date_gmt":"2018-10-29T15:07:04","guid":{"rendered":"https:\/\/isilos.ru\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php"},"modified":"2018-10-29T15:07:04","modified_gmt":"2018-10-29T15:07:04","slug":"somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas","status":"publish","type":"post","link":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php","title":{"rendered":"Somos participantes y oradores de la conferencia l\u00edder sobre mezclas secas."},"content":{"rendered":"<p>En agosto de 2018, participamos en la conferencia cient\u00edfica y de producci\u00f3n l\u00edder en las mezclas de construcci\u00f3n seca de Rusia y el CIS &#8211; Baltinix.<\/p>\n<p>M\u00e1s<\/p>\n<p><a  href=\"http:\/\/isilos.ru\/wp-content\/uploads\/2018\/10\/logo_baltimix2018.png\" data-rel=\"lightbox-gallery-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" alt=\"\" class=\"alignright size-full wp-image-2907\" height=\"173\" src=\"http:\/\/isilos.ru\/wp-content\/uploads\/2018\/10\/logo_baltimix2018.png\" width=\"200\"\/><\/a>La conferencia asisti\u00f3 l\u00edderes mundiales tan prominentes como Haver &amp; Boecker, Lahti. Hubo informes de cient\u00edficos rusos y alemanes sobre lo que ser\u00e1n los nuevos GOST y las normas.<\/p>\n<p>Presentamos en la conferencia Marc Suncyx, bajo la cual producimos f\u00e1bricas complejas de mezclas de construcci\u00f3n llave en seco + equipos en esta \u00e1rea.<\/p>\n<p>El informe mostr\u00f3 nuestros logros en los sistemas de automatizaci\u00f3n y producci\u00f3n, como tambores de secado, dosificaci\u00f3n, sistemas de embalaje.<\/p>\n<p>Se represent\u00f3 un sistema de control de f\u00e1brica, que funciona no solo desde el control remoto central en la f\u00e1brica, sino que tambi\u00e9n puede usarse en cualquier tableta, computadora.<\/p>\n<p>La versi\u00f3n de demostraci\u00f3n de dicho sistema est\u00e1 constantemente disponible en la direcci\u00f3n<a href=\"http:\/\/control.sunnymix.ru\" rel=\"noopener\" target=\"_blank\">http:\/\/control.sunnymix.ru<\/a><\/p>\n<p><a href=\"http:\/\/www.baltimix.ru\/confer\/confer_archive\/reports\/doclad18\/SunnyMix2018.pdf\" rel=\"noopener\" target=\"_blank\">Un informe completo en el sitio web de la conferencia.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En agosto de 2018, participamos en la conferencia cient\u00edfica y de producci\u00f3n l\u00edder en las mezclas de construcci\u00f3n seca de Rusia y el CIS &#8211; Baltinix. M\u00e1s La conferencia asisti\u00f3 l\u00edderes mundiales tan prominentes como Haver &amp; Boecker, Lahti. Hubo informes de cient\u00edficos rusos y alemanes sobre lo que ser\u00e1n los nuevos GOST y las [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-9758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"En agosto de 2018, participamos en la conferencia cient\u00edfica y de producci\u00f3n l\u00edder en las mezclas de construcci\u00f3n seca de Rusia y el CIS - Baltinix. M\u00e1s La conferencia asisti\u00f3 l\u00edderes mundiales tan prominentes como Haver &amp; Boecker, Lahti. Hubo informes de cient\u00edficos rusos y alemanes sobre lo que ser\u00e1n los nuevos GOST y las\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\u0417\u0430\u0432\u043e\u0434 \u0410\u0410\u041c\u0438\u043a\u0441\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Somos participantes y oradores de la conferencia l\u00edder sobre mezclas secas.\" \/>\n\t\t<meta property=\"og:description\" content=\"En agosto de 2018, participamos en la conferencia cient\u00edfica y de producci\u00f3n l\u00edder en las mezclas de construcci\u00f3n seca de Rusia y el CIS - Baltinix. M\u00e1s La conferencia asisti\u00f3 l\u00edderes mundiales tan prominentes como Haver &amp; Boecker, Lahti. Hubo informes de cient\u00edficos rusos y alemanes sobre lo que ser\u00e1n los nuevos GOST y las\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"364\" \/>\n\t\t<meta property=\"og:image:height\" content=\"94\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-10-29T15:07:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-10-29T15:07:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Somos participantes y oradores de la conferencia l\u00edder sobre mezclas secas.\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En agosto de 2018, participamos en la conferencia cient\u00edfica y de producci\u00f3n l\u00edder en las mezclas de construcci\u00f3n seca de Rusia y el CIS - Baltinix. M\u00e1s La conferencia asisti\u00f3 l\u00edderes mundiales tan prominentes como Haver &amp; Boecker, Lahti. Hubo informes de cient\u00edficos rusos y alemanes sobre lo que ser\u00e1n los nuevos GOST y las\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#article\",\"name\":\"Somos participantes y oradores de la conferencia l\\u00edder sobre mezclas secas.\",\"headline\":\"Somos participantes y oradores de la conferencia l\\u00edder sobre mezclas secas.\",\"author\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/author\\\/admin44#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/isilos.ru\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo_baltimix2018.png\",\"width\":200,\"height\":173},\"datePublished\":\"2018-10-29T15:07:04+00:00\",\"dateModified\":\"2018-10-29T15:07:04+00:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#webpage\"},\"articleSection\":\"\\u0411\\u0435\\u0437 \\u043a\\u0430\\u0442\\u0435\\u0433\\u043e\\u0440\\u0438\\u0438\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es#listItem\",\"position\":1,\"name\":\"\\u0413\\u043b\\u0430\\u0432\\u043d\\u0430\\u044f\",\"item\":\"https:\\\/\\\/isilos.ru\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/category\\\/news#listItem\",\"name\":\"\\u0411\\u0435\\u0437 \\u043a\\u0430\\u0442\\u0435\\u0433\\u043e\\u0440\\u0438\\u0438\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/category\\\/news#listItem\",\"position\":2,\"name\":\"\\u0411\\u0435\\u0437 \\u043a\\u0430\\u0442\\u0435\\u0433\\u043e\\u0440\\u0438\\u0438\",\"item\":\"https:\\\/\\\/isilos.ru\\\/es\\\/category\\\/news\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#listItem\",\"name\":\"Somos participantes y oradores de la conferencia l\\u00edder sobre mezclas secas.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es#listItem\",\"name\":\"\\u0413\\u043b\\u0430\\u0432\\u043d\\u0430\\u044f\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#listItem\",\"position\":3,\"name\":\"Somos participantes y oradores de la conferencia l\\u00edder sobre mezclas secas.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/category\\\/news#listItem\",\"name\":\"\\u0411\\u0435\\u0437 \\u043a\\u0430\\u0442\\u0435\\u0433\\u043e\\u0440\\u0438\\u0438\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/#organization\",\"name\":\"\\u041d\\u041f\\u041e \\u0417\\u0430\\u0432\\u043e\\u0434 \\u0410\\u0410\\u041c\\u0438\\u043a\\u0441\",\"description\":\"\\u041f\\u0440\\u043e\\u0438\\u0437\\u0432\\u043e\\u0434\\u0438\\u0442\\u0435\\u043b\\u044c \\u043f\\u0440\\u043e\\u043c\\u044b\\u0448\\u043b\\u0435\\u043d\\u043d\\u043e\\u0433\\u043e \\u043e\\u0431\\u043e\\u0440\\u0443\\u0434\\u043e\\u0432\\u0430\\u043d\\u0438\\u044f, \\u043a\\u043e\\u043c\\u043f\\u043b\\u0435\\u043a\\u0442\\u043d\\u044b\\u0445 \\u0437\\u0430\\u0432\\u043e\\u0434\\u043e\\u0432 \\u0441\\u0443\\u0445\\u0438\\u0445 \\u0441\\u043c\\u0435\\u0441\\u0435\\u0439, \\u0441\\u043c\\u0435\\u0441\\u0438\\u0442\\u0435\\u043b\\u0435\\u0439, \\u0434\\u043e\\u0437\\u0430\\u0442\\u043e\\u0440\\u043e\\u0432, \\u0441\\u0438\\u043b\\u043e\\u0441\\u043e\\u0432, \\u0444\\u0430\\u0441\\u043e\\u0432\\u043e\\u0447\\u043d\\u044b\\u0445 \\u043b\\u0438\\u043d\\u0438\\u0439 \\u0438 \\u0441\\u0438\\u0441\\u0442\\u0435\\u043c \\u0430\\u0432\\u0442\\u043e\\u043c\\u0430\\u0442\\u0438\\u0437\\u0430\\u0446\\u0438\\u0438.\",\"url\":\"https:\\\/\\\/isilos.ru\\\/es\\\/\",\"email\":\"info@isilos.ru\",\"telephone\":\"+7 (812) 408-41-82\",\"foundingDate\":\"1999\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/isilos.ru\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-logo.png\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php\\\/#organizationLogo\",\"width\":364,\"height\":94},\"image\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/@aamixplant\",\"https:\\\/\\\/t.me\\\/aamixplant\",\"https:\\\/\\\/isilos.ru\\\/contact.php\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/author\\\/admin44#author\",\"url\":\"https:\\\/\\\/isilos.ru\\\/es\\\/author\\\/admin44\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d9e6fa4592887841943e6d48122cce02679793a16afe2e942d40a45da0852e4?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#webpage\",\"url\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php\",\"name\":\"Somos participantes y oradores de la conferencia l\\u00edder sobre mezclas secas.\",\"description\":\"En agosto de 2018, participamos en la conferencia cient\\u00edfica y de producci\\u00f3n l\\u00edder en las mezclas de construcci\\u00f3n seca de Rusia y el CIS - Baltinix. M\\u00e1s La conferencia asisti\\u00f3 l\\u00edderes mundiales tan prominentes como Haver & Boecker, Lahti. Hubo informes de cient\\u00edficos rusos y alemanes sobre lo que ser\\u00e1n los nuevos GOST y las\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/author\\\/admin44#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/author\\\/admin44#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/isilos.ru\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo_baltimix2018.png\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php\\\/#mainImage\",\"width\":200,\"height\":173},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#mainImage\"},\"datePublished\":\"2018-10-29T15:07:04+00:00\",\"dateModified\":\"2018-10-29T15:07:04+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/isilos.ru\\\/es\\\/\",\"name\":\"\\u0417\\u0430\\u0432\\u043e\\u0434 \\u0410\\u0410\\u041c\\u0438\\u043a\\u0441\",\"alternateName\":\"AAMix, \\u0410\\u0410\\u041c\\u0438\\u043a\\u0441\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/isilos.ru\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Somos participantes y oradores de la conferencia l\u00edder sobre mezclas secas.","description":"En agosto de 2018, participamos en la conferencia cient\u00edfica y de producci\u00f3n l\u00edder en las mezclas de construcci\u00f3n seca de Rusia y el CIS - Baltinix. M\u00e1s La conferencia asisti\u00f3 l\u00edderes mundiales tan prominentes como Haver & Boecker, Lahti. Hubo informes de cient\u00edficos rusos y alemanes sobre lo que ser\u00e1n los nuevos GOST y las","canonical_url":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#article","name":"Somos participantes y oradores de la conferencia l\u00edder sobre mezclas secas.","headline":"Somos participantes y oradores de la conferencia l\u00edder sobre mezclas secas.","author":{"@id":"https:\/\/isilos.ru\/es\/author\/admin44#author"},"publisher":{"@id":"https:\/\/isilos.ru\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/isilos.ru\/wp-content\/uploads\/2018\/10\/logo_baltimix2018.png","width":200,"height":173},"datePublished":"2018-10-29T15:07:04+00:00","dateModified":"2018-10-29T15:07:04+00:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#webpage"},"isPartOf":{"@id":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#webpage"},"articleSection":"\u0411\u0435\u0437 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438"},{"@type":"BreadcrumbList","@id":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/isilos.ru\/es#listItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f","item":"https:\/\/isilos.ru\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/isilos.ru\/es\/category\/news#listItem","name":"\u0411\u0435\u0437 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438"}},{"@type":"ListItem","@id":"https:\/\/isilos.ru\/es\/category\/news#listItem","position":2,"name":"\u0411\u0435\u0437 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438","item":"https:\/\/isilos.ru\/es\/category\/news","nextItem":{"@type":"ListItem","@id":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#listItem","name":"Somos participantes y oradores de la conferencia l\u00edder sobre mezclas secas."},"previousItem":{"@type":"ListItem","@id":"https:\/\/isilos.ru\/es#listItem","name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f"}},{"@type":"ListItem","@id":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#listItem","position":3,"name":"Somos participantes y oradores de la conferencia l\u00edder sobre mezclas secas.","previousItem":{"@type":"ListItem","@id":"https:\/\/isilos.ru\/es\/category\/news#listItem","name":"\u0411\u0435\u0437 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438"}}]},{"@type":"Organization","@id":"https:\/\/isilos.ru\/es\/#organization","name":"\u041d\u041f\u041e \u0417\u0430\u0432\u043e\u0434 \u0410\u0410\u041c\u0438\u043a\u0441","description":"\u041f\u0440\u043e\u0438\u0437\u0432\u043e\u0434\u0438\u0442\u0435\u043b\u044c \u043f\u0440\u043e\u043c\u044b\u0448\u043b\u0435\u043d\u043d\u043e\u0433\u043e \u043e\u0431\u043e\u0440\u0443\u0434\u043e\u0432\u0430\u043d\u0438\u044f, \u043a\u043e\u043c\u043f\u043b\u0435\u043a\u0442\u043d\u044b\u0445 \u0437\u0430\u0432\u043e\u0434\u043e\u0432 \u0441\u0443\u0445\u0438\u0445 \u0441\u043c\u0435\u0441\u0435\u0439, \u0441\u043c\u0435\u0441\u0438\u0442\u0435\u043b\u0435\u0439, \u0434\u043e\u0437\u0430\u0442\u043e\u0440\u043e\u0432, \u0441\u0438\u043b\u043e\u0441\u043e\u0432, \u0444\u0430\u0441\u043e\u0432\u043e\u0447\u043d\u044b\u0445 \u043b\u0438\u043d\u0438\u0439 \u0438 \u0441\u0438\u0441\u0442\u0435\u043c \u0430\u0432\u0442\u043e\u043c\u0430\u0442\u0438\u0437\u0430\u0446\u0438\u0438.","url":"https:\/\/isilos.ru\/es\/","email":"info@isilos.ru","telephone":"+7 (812) 408-41-82","foundingDate":"1999","logo":{"@type":"ImageObject","url":"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png","@id":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php\/#organizationLogo","width":364,"height":94},"image":{"@id":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php\/#organizationLogo"},"sameAs":["https:\/\/www.youtube.com\/@aamixplant","https:\/\/t.me\/aamixplant","https:\/\/isilos.ru\/contact.php"]},{"@type":"Person","@id":"https:\/\/isilos.ru\/es\/author\/admin44#author","url":"https:\/\/isilos.ru\/es\/author\/admin44","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2d9e6fa4592887841943e6d48122cce02679793a16afe2e942d40a45da0852e4?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#webpage","url":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php","name":"Somos participantes y oradores de la conferencia l\u00edder sobre mezclas secas.","description":"En agosto de 2018, participamos en la conferencia cient\u00edfica y de producci\u00f3n l\u00edder en las mezclas de construcci\u00f3n seca de Rusia y el CIS - Baltinix. M\u00e1s La conferencia asisti\u00f3 l\u00edderes mundiales tan prominentes como Haver & Boecker, Lahti. Hubo informes de cient\u00edficos rusos y alemanes sobre lo que ser\u00e1n los nuevos GOST y las","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/isilos.ru\/es\/#website"},"breadcrumb":{"@id":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#breadcrumblist"},"author":{"@id":"https:\/\/isilos.ru\/es\/author\/admin44#author"},"creator":{"@id":"https:\/\/isilos.ru\/es\/author\/admin44#author"},"image":{"@type":"ImageObject","url":"https:\/\/isilos.ru\/wp-content\/uploads\/2018\/10\/logo_baltimix2018.png","@id":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php\/#mainImage","width":200,"height":173},"primaryImageOfPage":{"@id":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php#mainImage"},"datePublished":"2018-10-29T15:07:04+00:00","dateModified":"2018-10-29T15:07:04+00:00"},{"@type":"WebSite","@id":"https:\/\/isilos.ru\/es\/#website","url":"https:\/\/isilos.ru\/es\/","name":"\u0417\u0430\u0432\u043e\u0434 \u0410\u0410\u041c\u0438\u043a\u0441","alternateName":"AAMix, \u0410\u0410\u041c\u0438\u043a\u0441","inLanguage":"es-ES","publisher":{"@id":"https:\/\/isilos.ru\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"\u0417\u0430\u0432\u043e\u0434 \u0410\u0410\u041c\u0438\u043a\u0441","og:type":"article","og:title":"Somos participantes y oradores de la conferencia l\u00edder sobre mezclas secas.","og:description":"En agosto de 2018, participamos en la conferencia cient\u00edfica y de producci\u00f3n l\u00edder en las mezclas de construcci\u00f3n seca de Rusia y el CIS - Baltinix. M\u00e1s La conferencia asisti\u00f3 l\u00edderes mundiales tan prominentes como Haver &amp; Boecker, Lahti. Hubo informes de cient\u00edficos rusos y alemanes sobre lo que ser\u00e1n los nuevos GOST y las","og:url":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php","og:image":"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png","og:image:secure_url":"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png","og:image:width":364,"og:image:height":94,"article:published_time":"2018-10-29T15:07:04+00:00","article:modified_time":"2018-10-29T15:07:04+00:00","twitter:card":"summary","twitter:title":"Somos participantes y oradores de la conferencia l\u00edder sobre mezclas secas.","twitter:description":"En agosto de 2018, participamos en la conferencia cient\u00edfica y de producci\u00f3n l\u00edder en las mezclas de construcci\u00f3n seca de Rusia y el CIS - Baltinix. M\u00e1s La conferencia asisti\u00f3 l\u00edderes mundiales tan prominentes como Haver &amp; Boecker, Lahti. Hubo informes de cient\u00edficos rusos y alemanes sobre lo que ser\u00e1n los nuevos GOST y las","twitter:image":"https:\/\/isilos.ru\/wp-content\/uploads\/2025\/07\/cropped-logo.png"},"aioseo_meta_data":{"post_id":"9758","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-07-16 14:47:42","updated":"2025-07-16 14:47:42","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/isilos.ru\/es\" title=\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f\">\u0413\u043b\u0430\u0432\u043d\u0430\u044f<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/isilos.ru\/es\/category\/news\" title=\"\u0411\u0435\u0437 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438\">\u0411\u0435\u0437 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSomos participantes y oradores de la conferencia l\u00edder sobre mezclas secas.\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f","link":"https:\/\/isilos.ru\/es"},{"label":"\u0411\u0435\u0437 \u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u0438","link":"https:\/\/isilos.ru\/es\/category\/news"},{"label":"Somos participantes y oradores de la conferencia l\u00edder sobre mezclas secas.","link":"https:\/\/isilos.ru\/es\/somos-participantes-y-oradores-de-la-conferencia-lider-sobre-mezclas-secas.php"}],"_links":{"self":[{"href":"https:\/\/isilos.ru\/es\/wp-json\/wp\/v2\/posts\/9758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isilos.ru\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isilos.ru\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isilos.ru\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/isilos.ru\/es\/wp-json\/wp\/v2\/comments?post=9758"}],"version-history":[{"count":0,"href":"https:\/\/isilos.ru\/es\/wp-json\/wp\/v2\/posts\/9758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isilos.ru\/es\/wp-json\/wp\/v2\/media\/7033"}],"wp:attachment":[{"href":"https:\/\/isilos.ru\/es\/wp-json\/wp\/v2\/media?parent=9758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isilos.ru\/es\/wp-json\/wp\/v2\/categories?post=9758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isilos.ru\/es\/wp-json\/wp\/v2\/tags?post=9758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}